{"id":4015,"date":"2021-12-07T10:56:36","date_gmt":"2021-12-07T10:56:36","guid":{"rendered":"https:\/\/www.seraina-pazeller.com\/?page_id=4015"},"modified":"2022-09-12T14:07:09","modified_gmt":"2022-09-12T14:07:09","slug":"privacy","status":"publish","type":"page","link":"https:\/\/www.seraina-pazeller.com\/it\/privacy\/","title":{"rendered":"Privacy &#038; Cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4015\" class=\"elementor elementor-4015 elementor-3169\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-58806085 rechtliches elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58806085\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a8dd4a2\" data-id=\"6a8dd4a2\" data-element_type=\"column\" data-settings=\"{&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;,&quot;_ob_teleporter_use&quot;:false,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50ace3b0 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"50ace3b0\" data-element_type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informativa sul trattamento dei dati personali<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e774faf ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"1e774faf\" data-element_type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><em>Informativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016<\/em><\/strong><\/p><h5>Titolare del trattamento:<\/h5><p><strong>Seraina Pazeller<\/strong><br \/>Via Glorenza 34<br \/>39024 Malles (BZ)<br \/>Alto Adige<br \/>T +39 331 131 3367<br \/>www.seraina-pazeller.com<\/p><h5>Dati di contatto del responsabile della protezione dei dati:<\/h5><p><strong>Seraina Pazeller<\/strong><br \/>Via Glorenza 34<br \/>39024 Malles (BZ)<br \/>Alto Adige<br \/>T +39 331 131 3367<br \/>www.seraina-pazeller.com<\/p><h5>\u00a0<\/h5><h5>Informazioni sulla privacy &#8211; Sito web<\/h5><p>Gentile visitatore,<\/p><p>Siamo lieti di informarLa su come vengono trattati i suoi dati personali quando visita il nostro sito web. Da questa informativa potr\u00e0 vedere quali sono i diritti che pu\u00f2 esercitare in qualit\u00e0 di interessato.<\/p><p>I suoi dati personali saranno trattati in conformit\u00e0 al Regolamento UE 2016\/679 (Regolamento generale sulla protezione dei dati) ed alla legislazione nazionale in materia di protezione dei dati.<\/p><p>L&#8217;utilizzo del sito web implica l&#8217;accettazione della presente informativa sulla privacy, in caso contrario Le chiediamo di non continuare ad utilizzare questo sito web.<\/p><p>Desideriamo inoltre informarLa, che i link presenti sul nostro sito web sono stati da noi accuratamente selezionati e controllati. Poich\u00e9 i siti ad esso collegati possono essere soggetti ad aggiornamenti che avvengono a nostra insaputa ed i loro contenuti possono cambiare continuamente, non ci assumiamo alcuna responsabilit\u00e0 per essi.<\/p><p><strong>Finalit\u00e0 del trattamento dei dati personali<\/strong><\/p><p>Per garantire la funzionalit\u00e0 del sito web nonch\u00e9 per scopi statistici, vengono trattati dati tecnici con potenziale riferimento personale, come ad esempio l&#8217;indirizzo IP, l&#8217;ora degli accessi, il nome del dominio e dati simili. Inoltre, il gestore del sito web ha un interesse legittimo (art. 6f GDPR) a fornire un sito web visivamente accattivante e una piacevole esperienza d&#8217;uso. Previo consenso (art. 6a GDPR), \u00e8 inoltre possibile creare una profilazione degli utenti per perseguire finalit\u00e0 di marketing.<\/p><p>Lo scopo principale del trattamento dei dati \u00e8 la fornitura del nostro sito web e dei suoi contenuti, nonch\u00e9 l&#8217;adempimento delle richieste dell\u2019utente.<\/p><p>I dati personali vengono inoltre trattati per offrire diversi servizi:<\/p><p><strong>Modulo di contatto<\/strong><\/p><p>Il visitatore del sito web pu\u00f2 contattare l&#8217;azienda utilizzando il modulo di contatto. A tal fine, i dati personali inseriti saranno trattati per rispondere alla richiesta. \u00c8 disponibile un consenso esplicito al trattamento dei dati nel modulo di contatto.<\/p><p><strong>Trasmissione di categorie particolari di dati personali<\/strong><\/p><p>LA preghiamo di non trasmettere dati sensibili (dati personali di categorie speciali &#8211; art. 9 e art. 10 GDPR) tramite il sito web, ad esempio utilizzando il modulo di contatto.<\/p><p><strong>Base giuridica del trattamento dei dati:<\/strong><\/p><p>La base giuridica principale per il trattamento \u00e8 l&#8217;art. 6b) GDPR e l&#8217;art. 6f) GDPR (funzionalit\u00e0 del sito web) nonch\u00e9 il consenso ottenuto, se fornito da Lei (art. 6a GDPR).<\/p><p><strong>Cookies <\/strong><\/p><p>Il nostro sito web utilizza cookies, grazie ai quali i dati personali possono essere elaborati.<\/p><p>Esistono quattro categorie di cookies:<\/p><ul><li>Cookies strettamente necessari &#8211; per la funzionalit\u00e0 di base del sito web.<\/li><li>Cookies funzionali &#8211; per garantire le prestazioni ottimali del sito web, ad esempio il salvataggio della selezione della lingua.<\/li><li>Cookies di prestazione &#8211; Per migliorare l&#8217;esperienza dell&#8217;utente e per elaborare informazioni sull&#8217;utilizzo del sito web, ad esempio per misurare i tempi di caricamento.<\/li><li>Cookies di marketing &#8211; per la raccolta del comportamento e degli interessi dell&#8217;utente a fini di marketing, ad esempio per l&#8217;inserimento di pubblicit\u00e0 personalizzata<\/li><\/ul><p>I cookies non essenziali sono disattivati per impostazione predefinita sui nostri siti web e vengono attivati solo se l&#8217;utente ha dato il proprio esplicito consenso.<\/p><p>La maggior parte dei cookies utilizzati sono &#8220;cookies di sessione&#8221; che vengono eliminati dopo la chiusura del browser. Altri cookies vengono memorizzati, ad esempio, per visualizzare la lingua corretta alla successiva visita del sito web.<\/p><p>Per tutti i cookies che non sono soggetti ad un interesse legittimo del gestore del sito web (art. 6f) GDPR), Le verr\u00e0 chiesto esplicitamente il consenso.<\/p><p><strong>\u00a0<\/strong><\/p><p>\u00c8 possibile cancellare i cookie in qualsiasi momento, a seconda del browser utilizzato, cliccando di solito sui 3 puntini\/strisce in alto a destra e poi aprendo le impostazioni, digitando cookie nel campo di ricerca e selezionando: elimina cookie\/ elimina dati del browser.<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Fornitura dei dati<\/strong><br \/>Il conferimento dei dati \u00e8 volontario (ad eccezione del trattamento dei dati di navigazione) e non \u00e8 richiesto dalla legge. Tuttavia, il mancato conferimento pu\u00f2 comportare la limitazione dell&#8217;uso del sito web e dei servizi offerti.<\/p><p><strong>Trasferimento dei dati a terzi<\/strong><\/p><p>I Suoi dati possono essere trasmessi a terzi se necessario, ma solo nell&#8217;ambito del nostro rapporto commerciale, ad esempio per l&#8217;adempimento della Sua richiesta o, se applicabile, per l&#8217;esecuzione di pagamenti tramite terzi e per l&#8217;adempimento di obblighi legali. In linea di principio, i vostri dati non saranno trasferiti in Paesi extra UE senza il Suo esplicito consenso. Lo stesso vale anche per l&#8217;uso della profilazione e delle decisioni automatizzate.<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Hosting del sito web<\/strong><\/p><p>Questo sito web \u00e8 ospitato da un fornitore di servizi esterno.<\/p><p>A tal fine, il \u201choster\u201d esterno riceve i dati personali raccolti sul sito web. La base giuridica \u00e8 costituita dall&#8217;art. 6b) GDPR &#8211; misure precontrattuali e dall&#8217;art. 6f) (garanzia di longevit\u00e0 degli strumenti presenti sul nostro sito web).<\/p><p><strong>Servizi Google<\/strong><\/p><p>Il nostro sito web utilizza i servizi dell&#8217;operatore Google Ireland Limited (&#8220;Google&#8221;), Gordon House, Barrow Street, Dublino 4, Irlanda.<\/p><p>Google pu\u00f2 quindi, In determinate circostanze, trattare informazioni e dati personali. Si noti che le autorit\u00e0 americane potrebbero teoricamente accedere a questi dati a causa della legislazione americana (in particolare il Cloud Act). Le informazioni sul quadro giuridico per il trasferimento dei dati sono disponibili sul sito https:\/\/policies.google.com\/privacy\/frameworks.<\/p><p><u>Previo consenso:<\/u> <strong>Google Tag Manager<\/strong><\/p><p>Il nostro sito web utilizza Google Tag Manager. Il fornitore \u00e8 Google Ireland Limited (&#8220;Google&#8221;), House, Barrow Street, Dublino 4, Irlanda.<\/p><p>Google Tag Manager semplifica l&#8217;integrazione dei codici di tracciamento. Inoltre, offre agli operatori del sito la possibilit\u00e0 di apportare modifiche che vengono applicate automaticamente alle pagine senza dover adattare il codice sorgente.<\/p><p>Google Tag Manager pu\u00f2 comunicare con i server di Tag Manager, nel corso dei quali, possono essere elaborati dati personali quando viene attivato un tag (ad esempio, l&#8217;indirizzo IP).<\/p><p>Prima dell&#8217;attivazione di Google Tag Manager vi verr\u00e0 chiesto esplicitamente il vostro consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<\/p><p>Informazioni dettagliate sono disponibili all&#8217;indirizzo: https:\/\/policies.google.com\/privacy<\/p><p><u>Previo consenso:<\/u><strong> Analisi web \u2013 Google Analytics<\/strong><\/p><p>Il nostro sito web utilizza le funzioni del servizio di analisi web Google Analytics.<\/p><p>Il fornitore \u00e8 Google Inc, 1600 Amphitheatre Parkway Mountain View, CA 94043, U S A. Google Analytics.<\/p><p>Le informazioni ottenute attraverso i cookies sulle abitudini del cliente nell&#8217;utilizzo dei siti internet (compreso l&#8217;indirizzo IP) possono essere trasferite ad un server di Google sito negli Stati Uniti.<\/p><p>L\u2019informativa completa: https:\/\/support.google.com\/analytics\/answer\/6004245?hl=it<\/p><p>Utilizziamo Google Analytics come strumento di analisi per monitorare le prestazioni del nostro sito web, per analizzare il comportamento dei clienti e per adottare misure appropriate.<\/p><p>Prima dell&#8217;attivazione di Google Analytics Le verr\u00e0 chiesto esplicitamente il Suo consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<\/p><p>\u00c8 inoltre possibile impedire la raccolta e l&#8217;elaborazione dei dati descritti da parte di Google scaricando e installando il plug-in del browser disponibile al seguente link: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it<\/a><\/p><p><strong>Google-Maps<\/strong><\/p><p>Questo sito web utilizza Google Maps API, un servizio di mappatura fornito da Google Inc. (&#8220;Google&#8221;), per visualizzare una mappa interattiva e creare indicazioni stradali. Google Maps \u00e8 gestito da Google Inc, 1600 Amphitheatre Parkway, Mountain View, CA 94043, U S A.<\/p><p>Utilizzando Google Maps, non possiamo escludere che le informazioni sull&#8217;utilizzo di questo sito web da parte dell&#8217;utente (compreso il suo indirizzo IP) vengano trasmesse ad un server di Google negli Stati Uniti e l\u00ec memorizzate. Google pu\u00f2 trasferire le informazioni ottenute tramite Maps a terzi, qualora ci\u00f2 sia richiesto dalla legge o qualora tali terzi trattino le informazioni per conto di Google.<\/p><p>In linea di principio, sarebbe tecnicamente possibile per Google identificare i singoli utenti sulla base dei dati ricevuti. \u00c8 possibile che i dati personali ed i profili della personalit\u00e0 degli utenti del sito web vengano elaborati da Google per altri scopi sui quali non abbiamo e non possiamo avere alcuna influenza. Sussiste la possibilit\u00e0 di disattivare il servizio Google Maps e quindi di impedire il trasferimento dei dati a Google disattivando JavaScript nel browser. Tuttavia, desideriamo sottolineare che in questo caso non sar\u00e0 possibile utilizzare la visualizzazione della mappa sul nostro sito.<\/p><p>Le condizioni di utilizzo di Google Maps sono disponibili all&#8217;indirizzo: https:\/\/www.google.com\/intl\/it_it\/help\/terms_maps\/.<\/p><p>L&#8217;informativa sulla privacy di Google \u00e8 disponibile all&#8217;indirizzo: https:\/\/policies.google.com\/privacy<\/p><p><strong>YouTube<\/strong><\/p><p>Utilizziamo i social plugin di YouTube, un sito gestito da Google. Il gestore di questo sito \u00e8 YouTube, LLC, 901 Cherry Ave, San Bruno, CA 94066, U S A.<\/p><p>Quando si visita una pagina dotata di un plugin di YouTube, viene stabilita una connessione ai server di YouTube. In questo modo il server di YouTube viene informato che l&#8217;utente ha visitato il nostro sito e possono essere compilate statistiche sull&#8217;utente, ad esempio tramite i cookie.<\/p><p>Se l&#8217;utente ha effettuato l&#8217;accesso al proprio account YouTube, YouTube pu\u00f2 assegnare la visita al nostro sito web al suo account utente. \u00c8 possibile evitare che ci\u00f2 accada disconnettendosi dal proprio account YouTube.<\/p><p>Per ulteriori informazioni su come YouTube gestisca i dati degli utenti, consultare l&#8217;informativa sulla privacy all&#8217;indirizzo https:\/\/www.google.de\/intl\/de\/policies\/privacy.<\/p><p><u>Con il Suo consenso:<\/u><strong> &#8220;Facebook Pixel\u201d<\/strong><\/p><p>Il nostro sito web utilizza il cosiddetto &#8220;Facebook Pixel&#8221; del social network Facebook, gestito da Facebook Inc. o, se \u00e8 residente nell&#8217;UE, da Facebook Ireland Ltd, 4 Grand Canal Square, Grand Canal Harbour, Dublino 2, Irlanda.<\/p><p>Quando visita il sito web, viene stabilita una connessione diretta con il server di Facebook tramite il \u201cFacebook Pixel\u201d. Questo trasmette al server la Sua visita e Facebook pu\u00f2, in determinate circostanze, assegnare le informazioni al Suo account\/utente personale di Facebook.<\/p><p>Possiamo cos\u00ec monitorare l&#8217;effetto delle campagne pubblicitarie.<\/p><p>Non si pu\u00f2 escludere che le informazioni vengano trasmesse a server di Paesi extra UE.<\/p><p>Se l&#8217;utente acconsente all&#8217;utilizzo del Pixel di Facebook, questo verr\u00e0 integrato da Facebook e un cookie verr\u00e0 memorizzato sul dispositivo dell&#8217;utente come descritto sopra. Quando si accede a Facebook, le offerte visitate vengono registrate nel profilo dell&#8217;utente. I dati vengono anonimizzati per noi, ma Facebook ha la possibilit\u00e0 di trattarli.<\/p><p>Per ulteriori informazioni sulla raccolta e sull&#8217;utilizzo dei dati da parte di Facebook, nonch\u00e9 sui diritti dell&#8217;utente a questo riguardo e sulle possibilit\u00e0 di proteggere la propria privacy, si prega di consultare l&#8217;informativa sulla privacy di Facebook all&#8217;indirizzo: https:\/\/www.facebook.com\/business\/m\/privacy-and-data<\/p><p>Prima dell&#8217;attivazione di Facebook Pixel Le verr\u00e0 chiesto esplicitamente il consenso. La base giuridica \u00e8 l&#8217;art. 6a) GDPR.<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>Crittografia SSL<\/strong><\/p><p>Questo sito utilizza la crittografia SSL per motivi di sicurezza di trasmissione, ad esempio per le richieste nei moduli di contatto. La crittografia SSL attiva viene utilizzata per criptare la trasmissione dei dati che ci vengono inviati.<\/p><p><strong>Visitatori minorenni <\/strong><\/p><p>Questo sito web non \u00e8 destinato all&#8217;uso da parte di minori. Pertanto, non raccogliamo e memorizziamo dati di visitatori minorenni (se non involontariamente).<\/p><p><strong>Durata della conservazione dei dati<\/strong><\/p><p>La durata della conservazione viene misurata in base agli obblighi di conservazione previsti dalla legge e agli obblighi legali a noi applicabili.<\/p><p><strong>Riferimenti ai diritti degli interessati<\/strong><br \/>L&#8217;interessato ha il diritto di ottenere dal titolare del trattamento la conferma dell&#8217;esistenza o meno dei dati personali che lo riguardano; in tal caso, ha il <strong>diritto di accesso <\/strong>ai dati personali (<u>art. 15 GDPR).<\/u><\/p><p>L&#8217;interessato ha il diritto di esigere che la persona titolare <strong>corregga<\/strong> immediatamente i dati personali inesatti che lo riguardano e, se necessario, <strong>completi i<\/strong> dati personali incompleti (<u>art. 16 GDPR<\/u>).<\/p><p>L&#8217;interessato ha il diritto di esigere la cancellazione immediata dei dati personali che lo riguardano, qualora ricorra uno dei motivi di cui all&#8217; <u>art. 17 GDPR<\/u>, ad esempio se i dati non sono pi\u00f9 necessari per gli scopi perseguiti (<strong>diritto alla cancellazione<\/strong>).<\/p><p>L&#8217;interessato ha il diritto di richiedere al titolare del trattamento<strong> di limitare il trattamento <\/strong>se \u00e8 soddisfatta una delle condizioni di cui all&#8217; <u>articolo 18 del GDPR<\/u>, ad esempio se l&#8217;interessato si \u00e8 opposto al trattamento.<\/p><p>L&#8217;interessato ha il diritto di ricevere in un formato strutturato, di uso comune e leggibile da dispositivo automatico i dati personali che lo riguardano forniti a un titolare del trattamento e ha il diritto di trasmettere tali dati a un altro titolare del trattamento senza impedimenti da parte del titolare del trattamento cui li ha forniti per esempio se il trattamento si basi sul consenso dell\u2019 interessato e il trattamento sia effettuato con mezzi automatizzati (<strong>diritto alla portabilit\u00e0 dei dati<\/strong> <u>art. 20 GDPR<\/u>).<\/p><p>L&#8217;interessato ha il <strong>diritto di opporsi<\/strong> in qualsiasi momento al trattamento dei dati personali che lo riguardano per motivi connessi alla sua situazione particolare. Il titolare del trattamento non tratta pi\u00f9 i dati personali, a meno che non sia in grado di dimostrare di avere motivi convincenti per un trattamento degno di protezione che superano gli interessi, i diritti e le libert\u00e0 dell&#8217;interessato o che il trattamento serve a far valere, esercitare o difendere un diritto in giudizio (<u>art. 21 GDPR<\/u>).<\/p><p>Fatto salvo ogni altro ricorso amministrativo o giurisdizionale, l&#8217;interessato che ritenga che il trattamento che lo riguarda violi il presente regolamento ha il <strong>diritto di proporre reclamo<\/strong> a un&#8217;autorit\u00e0 di controllo (<u>art. 77 GDPR<\/u>), segnatamente nello Stato membro in cui risiede abitualmente, lavora oppure del luogo ove si \u00e8 verificata la presunta violazione.\u00a0In Italia, l&#8217;autorit\u00e0 di vigilanza competente \u00e8 il Garante per la protezione dei dati personali<\/p><p><u>La presente informativa sulla protezione dei dati pu\u00f2 essere aggiornata in qualsiasi momento.<\/u><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informativa sul trattamento dei dati personali Informativa ai sensi degli artt. 12, 13 e 14 del Regolamento UE 679\/2016 Titolare del trattamento: Seraina PazellerVia Glorenza 3439024 Malles (BZ)Alto AdigeT +39 331 131 3367www.seraina-pazeller.com Dati di contatto del responsabile della protezione dei dati: Seraina PazellerVia Glorenza 3439024 Malles (BZ)Alto AdigeT +39 331 131 3367www.seraina-pazeller.com \u00a0 Informazioni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy<\/title>\n<meta name=\"description\" content=\"Privacy\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.seraina-pazeller.com\/it\/privacy\/\",\"url\":\"https:\/\/www.seraina-pazeller.com\/it\/privacy\/\",\"name\":\"Privacy\",\"isPartOf\":{\"@id\":\"https:\/\/www.seraina-pazeller.com\/#website\"},\"datePublished\":\"2021-12-07T10:56:36+00:00\",\"dateModified\":\"2022-09-12T14:07:09+00:00\",\"description\":\"Privacy\",\"breadcrumb\":{\"@id\":\"https:\/\/www.seraina-pazeller.com\/it\/privacy\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.seraina-pazeller.com\/it\/privacy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.seraina-pazeller.com\/it\/privacy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.seraina-pazeller.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy &#038; Cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.seraina-pazeller.com\/#website\",\"url\":\"https:\/\/www.seraina-pazeller.com\/\",\"name\":\"Seraina Pazeller\",\"description\":\"Gesundheit und Wohlbefinden\",\"publisher\":{\"@id\":\"https:\/\/www.seraina-pazeller.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.seraina-pazeller.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.seraina-pazeller.com\/#organization\",\"name\":\"Seraina Pazeller\",\"url\":\"https:\/\/www.seraina-pazeller.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.seraina-pazeller.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.seraina-pazeller.com\/wp-content\/uploads\/LOGO_Seraina_Pazeller_Therapiezentrum-SW.svg\",\"contentUrl\":\"https:\/\/www.seraina-pazeller.com\/wp-content\/uploads\/LOGO_Seraina_Pazeller_Therapiezentrum-SW.svg\",\"width\":332,\"height\":140,\"caption\":\"Seraina Pazeller\"},\"image\":{\"@id\":\"https:\/\/www.seraina-pazeller.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy","description":"Privacy","robots":{"index":"noindex","follow":"nofollow"},"twitter_misc":{"Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.seraina-pazeller.com\/it\/privacy\/","url":"https:\/\/www.seraina-pazeller.com\/it\/privacy\/","name":"Privacy","isPartOf":{"@id":"https:\/\/www.seraina-pazeller.com\/#website"},"datePublished":"2021-12-07T10:56:36+00:00","dateModified":"2022-09-12T14:07:09+00:00","description":"Privacy","breadcrumb":{"@id":"https:\/\/www.seraina-pazeller.com\/it\/privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seraina-pazeller.com\/it\/privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.seraina-pazeller.com\/it\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.seraina-pazeller.com\/it\/"},{"@type":"ListItem","position":2,"name":"Privacy &#038; Cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.seraina-pazeller.com\/#website","url":"https:\/\/www.seraina-pazeller.com\/","name":"Seraina Pazeller","description":"Gesundheit und Wohlbefinden","publisher":{"@id":"https:\/\/www.seraina-pazeller.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seraina-pazeller.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.seraina-pazeller.com\/#organization","name":"Seraina Pazeller","url":"https:\/\/www.seraina-pazeller.com\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.seraina-pazeller.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.seraina-pazeller.com\/wp-content\/uploads\/LOGO_Seraina_Pazeller_Therapiezentrum-SW.svg","contentUrl":"https:\/\/www.seraina-pazeller.com\/wp-content\/uploads\/LOGO_Seraina_Pazeller_Therapiezentrum-SW.svg","width":332,"height":140,"caption":"Seraina Pazeller"},"image":{"@id":"https:\/\/www.seraina-pazeller.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/pages\/4015"}],"collection":[{"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/comments?post=4015"}],"version-history":[{"count":14,"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/pages\/4015\/revisions"}],"predecessor-version":[{"id":5367,"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/pages\/4015\/revisions\/5367"}],"wp:attachment":[{"href":"https:\/\/www.seraina-pazeller.com\/it\/wp-json\/wp\/v2\/media?parent=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}